{"id":66,"date":"2023-03-28T07:31:23","date_gmt":"2023-03-28T07:31:23","guid":{"rendered":"https:\/\/eusebiguiral.com\/?page_id=66"},"modified":"2024-08-28T07:50:45","modified_gmt":"2024-08-28T07:50:45","slug":"inici","status":"publish","type":"page","link":"https:\/\/eusebiguiral.com\/esp\/","title":{"rendered":"Majorista de fruita i verdura a Mercabarna"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.3) 0%|rgba(0,0,0,0.3) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/03\/AAG_0139.jpg\u00bb height=\u00bb103vh\u00bb custom_margin=\u00bb-100px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb height=\u00bb100%\u00bb custom_css_main_element=\u00bbdisplay: flex;||flex-direction: column;||justify-content: center;||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbQuicksand||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb30px\u00bb text_line_height=\u00bb1.4em\u00bb header_font=\u00bbNunito||||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb68px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"font-family: Nunito; padding-left: 1px;\"><span style=\"font-weight: 300; color: fd4d0b;\">Eusebi<\/span> <strong style=\"color: #fdb306;\">Guiral<\/strong><\/span><br \/><span style=\"font-size: 60px;\">Variedad de sabores<br \/>directos de la naturaleza<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_padding_tablet=\u00bb0px||0px||false|false\u00bb custom_padding_phone=\u00bb50px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbdisplay: flex;||flex-direction: column;||justify-content: center;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbNunito|700|||||||\u00bb header_font_size=\u00bb32px\u00bb header_2_font=\u00bbNunito|700|||||||\u00bb header_2_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>El sabor de la tierra, directo a tu comercio<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbQuicksand|500|||||||\u00bb global_colors_info=\u00bb{}\u00bb]Eusebi Guiral, el teu soci fiable en la distribuci\u00f3 de fruites fresques!<br \/>\n<strong>Con una trayectoria de casi 100 a\u00f1os,<\/strong> somos una empresa familiar \u00fanica en Mercabarna, dirigida por la cuarta generaci\u00f3n de la familia Guiral.<br \/>\nNuestra experiencia en el sector y nuestra pasi\u00f3n por la calidad nos han posicionado como referentes en importaci\u00f3n y exportaci\u00f3n de frutas.<\/p>\n<p>En Eusebi Guiral, no s\u00f3lo ofrecemos productos excepcionales, sino que nos esforzamos por crear v\u00ednculos duraderos con cada cliente y proveedor, para que se sientan parte de nuestra gran familia.<br \/>\nEl nostre comprom\u00eds amb excel\u00b7l\u00e8ncia, atenci\u00f3 personalitzada i responsabilitat social ens impulsa a marcar la difer\u00e8ncia.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/04\/AdobeStock_397057468-scaled.jpeg\u00bb alt=\u00bbPr\u00e9ssec en un fons blanc\u00bb title_text=\u00bbPr\u00e9ssec en un fons blanc\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#fcfcfc\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb||||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbNunito|700||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb32px\u00bb custom_margin=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Nuestros productos<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbNunito||||||||\u00bb text_font_size=\u00bb18px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]A Eusebi Guiral, hem establert una xarxa de prove\u00efdors de confian\u00e7a, que ens permet oferir, en qualsevol moment de l&#8217;any, la millor selecci\u00f3 de productes que enriqueixen, amb la m\u00e9s alta qualitat i frescor, la teva oferta gastron\u00f2mica.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb width=\u00bb70%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbborder: 10px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|5px||5px|false|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/04\/AdobeStock_478195623.png\u00bb alt=\u00bbMaduixes\u00bb title_text=\u00bbMaduixes\u00bb url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI2OSJ9fQ==@\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _dynamic_attributes=\u00bburl\u00bb _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px||false|false\u00bb mix_blend_mode=\u00bboverlay\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb90%|90%\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbNunito|700||on|||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb50px\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbcenter_center\u00bb text_orientation=\u00bbcenter\u00bb custom_css_main_element=\u00bbpointer-events: none;\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-shadow: 0px 0px 15px rgba(0,0,0,0.8);\">Fruta<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|5px||5px|false|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/05\/AdobeStock_366737640-scaled-1.webp\u00bb alt=\u00bbEnciam d&#8217;Eusebi Guiral\u00bb title_text=\u00bbEnciam d&#8217;Eusebi Guiral\u00bb url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI3MSJ9fQ==@\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _dynamic_attributes=\u00bburl\u00bb _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb90%|90%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbNunito|700||on|||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb50px\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbcenter_center\u00bb text_orientation=\u00bbcenter\u00bb custom_css_main_element=\u00bbpointer-events: none;\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-shadow: 0px 0px 15px rgba(0,0,0,0.8);\">Verdura<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbNunito|700||on|||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Blog<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_slider include_categories=\u00bb1&#8243; more_text=\u00bbLlegir m\u00e9s\u00bb show_meta=\u00bboff\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbRubik|300|||||||\u00bb body_font=\u00bbQuicksand|500|||||||\u00bb body_font_size=\u00bb16px\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bbNunito||||||||\u00bb text_orientation=\u00bbleft\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#A6D314&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbNunito|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb36px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfQuieres m\u00e1s informaci\u00f3n sobre nuestros productos?<\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijg3In19@\u00bb button_text=\u00bbContacta amb nosaltres\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bbNunito||||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#fcfcfc\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbNunito|700|||||||\u00bb header_2_text_align=\u00bbleft\u00bb header_2_font_size=\u00bb32px\u00bb header_3_font=\u00bbNunito|700|||||||\u00bb header_3_text_align=\u00bbleft\u00bb header_3_font_size=\u00bb28px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Informaci\u00f3n de contacto<\/h3>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bb \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#80BF20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb40px\u00bb admin_label=\u00bbAnuncio\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb body_font=\u00bbNunito||||||||\u00bb body_font_size=\u00bb18px\u00bb custom_css_blurb_image=\u00bbpadding-right: 10px;||vertical-align: middle;||position: relative;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]933 35 39 46[\/et_pb_blurb][et_pb_blurb title=\u00bb \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#80BF20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb40px\u00bb admin_label=\u00bbAnuncio\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb body_font=\u00bbNunito||||||||\u00bb body_font_size=\u00bb18px\u00bb link_option_url=\u00bbmailto:eusebi@eusebiguiral.com\u00bb custom_css_blurb_image=\u00bbpadding-right: 10px;||vertical-align: middle;||position: relative;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>eusebi@eusebiguiral.com<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe080;||divi||400&#8243; icon_color=\u00bb#80BF20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb40px\u00bb admin_label=\u00bbAnuncio\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb body_font=\u00bbNunito||||||||\u00bb body_font_size=\u00bb18px\u00bb custom_css_blurb_image=\u00bbpadding-right: 10px;||vertical-align: middle;||position: relative;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Mercabarna, Pabell\u00f3n, A, 1054, 56, 08040 Barcelona[\/et_pb_blurb][et_pb_blurb title=\u00bb \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf017;||fa||900&#8243; icon_color=\u00bb#80BF20&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb40px\u00bb admin_label=\u00bbAnuncio\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb body_font=\u00bbNunito||||||||\u00bb body_font_size=\u00bb18px\u00bb custom_css_blurb_image=\u00bbpadding-right: 10px;||vertical-align: middle;||position: relative;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Oberts de 8:00 a 18:00[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbNunito|700|||||||\u00bb header_2_text_align=\u00bbleft\u00bb header_2_font_size=\u00bb32px\u00bb header_3_font=\u00bbNunito|700|||||||\u00bb header_3_text_align=\u00bbleft\u00bb header_3_font_size=\u00bb28px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Formulario<\/h3>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=\u00bbon\u00bb recaptcha_list=\u00bbDefault|Default-0&#8243; email=\u00bbeusebi@eusebiguiral.com\u00bb custom_message=\u00bbCorreu des de la WEB eusebiguiral.com||et_pb_line_break_holder||||et_pb_line_break_holder||Nom: %%Name%%||et_pb_line_break_holder||Tel\u00e8fon: %%Telefon%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Missatge: %%Message%%\u00bb submit_button_text=\u00bbEnvia\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb _unique_id=\u00bb20bffa56-eae1-4940-9a0e-452dfd6986fb\u00bb form_field_background_color=\u00bb#FFFFFF\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#80BF20&#8243; button_border_width=\u00bb0px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_margin_tablet=\u00bb||||false|true\u00bb custom_margin_last_edited=\u00bboff|phone\u00bb hover_enabled=\u00bb0&#8243; border_width_all=\u00bb2px\u00bb border_color_all=\u00bb#80BF20&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNom *\u00bb _builder_version=\u00bb4.27.0&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb fullwidth_field=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbTelefon\u00bb field_title=\u00bbTel\u00e8fon\u00bb _builder_version=\u00bb4.27.0&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243; required_mark=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbAdre\u00e7a de correu electr\u00f2nic *\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.27.0&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMissatge *\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbField_4&#8243; field_title=\u00bb \u00bb field_type=\u00bbcheckbox\u00bb checkbox_options=\u00bb%91{%22value%22:%22 Accepto la %22,%22checked%22:0,%22dragID%22:-1,%22link_text%22:%22Pol\u00edtica de privacitat%22,%22link_url%22:%22https:\/\/eusebiguiral.com\/politica-de-privacitat%22}%93&#8243; fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb link_font=\u00bb|600|||||||\u00bb link_text_color=\u00bb#000000&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb link_text_color__hover_enabled=\u00bboff|desktop\u00bb]<\/p>\n<p>Este sitio est\u00e1 protegido por reCAPTCHA y se aplican la <a href=\"https:\/\/policies.google.com\/privacy\">Pol\u00edtica de privacidad<\/a> y las <a href=\"https:\/\/policies.google.com\/terms\">Condiciones del servicio<\/a> de Google.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Eusebi GuiralVarietat de saborsdirectes de la naturaEl sabor de la terra, directe al teu comer\u00e7Eusebi Guiral, el teu soci fiable en la distribuci\u00f3 de fruites fresques! Amb una traject\u00f2ria de quasi 100 anys, som una empresa familiar \u00fanica a Mercabarna, dirigida per la quarta generaci\u00f3 de la fam\u00edlia Guiral. La nostra experi\u00e8ncia al sector i [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-66","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Majorista de fruita i verdura a Mercabarna - Eusebi Guiral<\/title>\n<meta name=\"description\" content=\"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eusebiguiral.com\/esp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Majorista de fruita i verdura a Mercabarna - Eusebi Guiral\" \/>\n<meta property=\"og:description\" content=\"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eusebiguiral.com\/esp\/\" \/>\n<meta property=\"og:site_name\" content=\"Eusebi Guiral\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61550539299491\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T07:50:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eusebiguiral.com\/\",\"url\":\"https:\/\/eusebiguiral.com\/\",\"name\":\"Majorista de fruita i verdura a Mercabarna - Eusebi Guiral\",\"isPartOf\":{\"@id\":\"https:\/\/eusebiguiral.com\/#website\"},\"datePublished\":\"2023-03-28T07:31:23+00:00\",\"dateModified\":\"2024-08-28T07:50:45+00:00\",\"description\":\"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.\",\"breadcrumb\":{\"@id\":\"https:\/\/eusebiguiral.com\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eusebiguiral.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eusebiguiral.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/eusebiguiral.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Majorista de fruita i verdura a Mercabarna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eusebiguiral.com\/#website\",\"url\":\"https:\/\/eusebiguiral.com\/\",\"name\":\"Eusebi Guiral\",\"description\":\"Sabors de temporada que satisfan als teus clients en tot moment\",\"publisher\":{\"@id\":\"https:\/\/eusebiguiral.com\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eusebiguiral.com\/#organization\",\"name\":\"Eusebi Guiral\",\"url\":\"https:\/\/eusebiguiral.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eusebiguiral.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/08\/logo-eusebi-3dde5f3b43e61195d83a14f1dccefbd31.png\",\"contentUrl\":\"https:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/08\/logo-eusebi-3dde5f3b43e61195d83a14f1dccefbd31.png\",\"width\":176,\"height\":176,\"caption\":\"Eusebi Guiral\"},\"image\":{\"@id\":\"https:\/\/eusebiguiral.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61550539299491\",\"https:\/\/www.instagram.com\/eusebiguiralsa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Majorista de fruita i verdura a Mercabarna - Eusebi Guiral","description":"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eusebiguiral.com\/esp\/","og_locale":"es_ES","og_type":"article","og_title":"Majorista de fruita i verdura a Mercabarna - Eusebi Guiral","og_description":"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.","og_url":"https:\/\/eusebiguiral.com\/esp\/","og_site_name":"Eusebi Guiral","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61550539299491","article_modified_time":"2024-08-28T07:50:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eusebiguiral.com\/","url":"https:\/\/eusebiguiral.com\/","name":"Majorista de fruita i verdura a Mercabarna - Eusebi Guiral","isPartOf":{"@id":"https:\/\/eusebiguiral.com\/#website"},"datePublished":"2023-03-28T07:31:23+00:00","dateModified":"2024-08-28T07:50:45+00:00","description":"Sabors frescos al teu abast! Descobreix Eusebi Guiral: el teu distribu\u00efdor de confian\u00e7a de fruites i verdures.","breadcrumb":{"@id":"https:\/\/eusebiguiral.com\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eusebiguiral.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eusebiguiral.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eusebiguiral.com\/"},{"@type":"ListItem","position":2,"name":"Majorista de fruita i verdura a Mercabarna"}]},{"@type":"WebSite","@id":"https:\/\/eusebiguiral.com\/#website","url":"https:\/\/eusebiguiral.com\/","name":"Eusebi Guiral","description":"Sabors de temporada que satisfan als teus clients en tot moment","publisher":{"@id":"https:\/\/eusebiguiral.com\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eusebiguiral.com\/#organization","name":"Eusebi Guiral","url":"https:\/\/eusebiguiral.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eusebiguiral.com\/#\/schema\/logo\/image\/","url":"https:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/08\/logo-eusebi-3dde5f3b43e61195d83a14f1dccefbd31.png","contentUrl":"https:\/\/eusebiguiral.com\/wp-content\/uploads\/2023\/08\/logo-eusebi-3dde5f3b43e61195d83a14f1dccefbd31.png","width":176,"height":176,"caption":"Eusebi Guiral"},"image":{"@id":"https:\/\/eusebiguiral.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61550539299491","https:\/\/www.instagram.com\/eusebiguiralsa\/"]}]}},"_links":{"self":[{"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/pages\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":94,"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/pages\/66\/revisions"}],"predecessor-version":[{"id":978,"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/pages\/66\/revisions\/978"}],"wp:attachment":[{"href":"https:\/\/eusebiguiral.com\/esp\/wp-json\/wp\/v2\/media?parent=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}